{"id":50916,"date":"2026-01-27T13:05:19","date_gmt":"2026-01-27T13:05:19","guid":{"rendered":"https:\/\/denoticiasonline.com\/?p=50916"},"modified":"2026-01-27T13:05:22","modified_gmt":"2026-01-27T13:05:22","slug":"paro-de-colectivos-en-el-amba-se-define-en-una-audiencia-clave","status":"publish","type":"post","link":"https:\/\/denoticiasonline.com\/index.php\/2026\/01\/27\/paro-de-colectivos-en-el-amba-se-define-en-una-audiencia-clave\/","title":{"rendered":"PARO DE COLECTIVOS EN EL AMBA SE DEFINE EN UNA AUDIENCIA CLAVE"},"content":{"rendered":"\n<p>Este martes se desarrollar\u00e1 una nueva audiencia entre la UTA y las empresas de colectivos, con el conflicto salarial a\u00fan sin resolver. El gremio volvi\u00f3 a cuestionar la oferta del 1% de aumento y apunt\u00f3 al manejo de los subsidios como un punto clave de la negociaci\u00f3n.<br><br>Luego del fracaso de la negociaci\u00f3n paritaria entre la Uni\u00f3n Tranviarios Automotor (UTA) y las c\u00e1maras empresarias, las partes volver\u00e1n a reunirse este martes a las 15 en un encuentro virtual, con el objetivo de intentar alcanzar un acuerdo salarial.<\/p>\n\n\n\n<p>Desde el gremio que nuclea a los trabajadores del transporte de pasajeros ratificaron que, en caso de no obtener una respuesta satisfactoria, podr\u00edan avanzar con un plan de lucha que incluir\u00eda un paro total del servicio de&nbsp;colectivos&nbsp;en el \u00c1rea Metropolitana de Buenos Aires (AMBA).<\/p>\n\n\n\n<p>La nueva instancia de di\u00e1logo ser\u00e1 clave para destrabar el conflicto y evitar una medida de fuerza que afectar\u00eda a millones de usuarios del transporte p\u00fablico.<\/p>\n\n\n\n<p>Durante el \u00faltimo encuentro, la UTA present\u00f3 una nueva propuesta salarial, tras rechazar el aumento del 1%, al que consider\u00f3 insuficiente y calific\u00f3 como una \u201cburla\u201d. Desde el gremio, que conduce Roberto Fern\u00e1ndez, remarcaron que los salarios actuales no alcanzan para \u201csostener un hogar\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes se desarrollar\u00e1 una nueva audiencia entre la UTA y las empresas de colectivos, con el conflicto salarial a\u00fan sin resolver. El gremio volvi\u00f3 a cuestionar la oferta del 1% de aumento y apunt\u00f3 al manejo de los subsidios como un punto clave de la negociaci\u00f3n. Luego del fracaso de la negociaci\u00f3n paritaria entre [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":50917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[108],"tags":[318,2188,434,5886],"class_list":{"0":"post-50916","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociedad-nacional","8":"tag-amba","9":"tag-colectivos","10":"tag-sociedad","11":"tag-uta"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/denoticiasonline.com\/wp-content\/uploads\/2026\/01\/Captura-de-pantalla-2026-01-27-094620.png?fit=517%2C290&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/50916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/comments?post=50916"}],"version-history":[{"count":1,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/50916\/revisions"}],"predecessor-version":[{"id":50918,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/50916\/revisions\/50918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/media\/50917"}],"wp:attachment":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/media?parent=50916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/categories?post=50916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/tags?post=50916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}