{"id":35863,"date":"2022-10-21T12:37:21","date_gmt":"2022-10-21T12:37:21","guid":{"rendered":"http:\/\/denoticiasonline.com\/?p=35863"},"modified":"2022-10-21T12:37:25","modified_gmt":"2022-10-21T12:37:25","slug":"boca-puntero","status":"publish","type":"post","link":"https:\/\/denoticiasonline.com\/index.php\/2022\/10\/21\/boca-puntero\/","title":{"rendered":"BOCA PUNTERO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>En La Plata el equipo Xeneize venci\u00f3 por 2 a 1 al Lobo, en el encuentro postergado de la fecha 23 del torneo de la Liga Profesional de F\u00fatbol. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El lateral Izquierdo&nbsp;<strong><em>Frank Fabra<\/em><\/strong>&nbsp;abri\u00f3 el marcador a los 29 minutos del primer tiempo con un verdadero golazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los 11 del complementario el&nbsp;<strong><em>Lobo<\/em><\/strong>&nbsp;empa\u00f1aba el festejo del conjunto de&nbsp;<strong><em>Ibarra<\/em><\/strong>, con un cabezazo de Leonardo Morales, pero a los 20 minutos apareci\u00f3 el juvenil, Luca Langoni para darle los tres puntos a los de&nbsp;<strong><em>Azul y Oro<\/em><\/strong>, quienes sue\u00f1an con ganar el campeonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con este resultado&nbsp;<strong><em>Boca Juniors<\/em><\/strong>&nbsp;vuelve a estar en lo m\u00e1s alto de la tabla de posiciones con 51 puntos, lo sigue&nbsp;<strong><em>Racing&nbsp;<\/em><\/strong>con 50 y&nbsp;<strong><em>Hurac\u00e1n<\/em><\/strong>&nbsp;con 47.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todav\u00eda no est\u00e1 nada dicho ya que el d\u00eda domingo ser\u00e1 la \u00faltima fecha del torneo.&nbsp;<strong><em>Boca<\/em><\/strong>&nbsp;vs&nbsp;<strong><em>Independiente<\/em><\/strong>&nbsp;y&nbsp;<strong><em>Racing&nbsp;<\/em><\/strong>ante&nbsp;<strong><em>River<\/em><\/strong>&nbsp;ambos encuentros ser\u00e1n a las 17:00 hs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En La Plata el equipo Xeneize venci\u00f3 por 2 a 1 al Lobo, en el encuentro postergado de la fecha 23 del torneo de la Liga Profesional de F\u00fatbol. El lateral Izquierdo&nbsp;Frank Fabra&nbsp;abri\u00f3 el marcador a los 29 minutos del primer tiempo con un verdadero golazo. A los 11 del complementario el&nbsp;Lobo&nbsp;empa\u00f1aba el festejo del [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":35868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[37],"tags":[4347,5675,270,5612,2486],"class_list":["post-35863","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes-merlo","tag-boca-juniors","tag-boca-puntero","tag-deportes","tag-gimnasia","tag-liga-profesional-de-futbol-2"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/denoticiasonline.com\/wp-content\/uploads\/2022\/10\/YDMRRK7GX4OSL6HRWJIBGAZK5Q.jpg?fit=360%2C203&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/35863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/comments?post=35863"}],"version-history":[{"count":1,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/35863\/revisions"}],"predecessor-version":[{"id":35869,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/posts\/35863\/revisions\/35869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/media\/35868"}],"wp:attachment":[{"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/media?parent=35863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/categories?post=35863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denoticiasonline.com\/index.php\/wp-json\/wp\/v2\/tags?post=35863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}